{"id":337,"date":"2018-07-16T14:51:35","date_gmt":"2018-07-16T12:51:35","guid":{"rendered":"http:\/\/lelavandehouse.com\/come-arrivare\/"},"modified":"2025-04-29T11:38:06","modified_gmt":"2025-04-29T09:38:06","slug":"anfahrt","status":"publish","type":"page","link":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/","title":{"rendered":"Anfahrt"},"content":{"rendered":"<h1><span style=\"font-weight: 400;\">\u00d6ko-Ferienhaus Le Lavande<\/span><\/h1>\n<p><span style=\"font-weight: 400;\">Kommen Sie und verbringen Sie einen erholsamen Aufenthalt inmitten der Natur, des guten Essens und der landschaftlichen sowie kulturellen Sch\u00f6nheiten der Toskana, alles in einer einladenden und \u00f6kologischen Ferienanlage!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Unsere Ferienanlage befindet sich: <\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">27 km von Firenze<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">37 Km von San Gimignano<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">42 Km von Vinci<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">57 km von Siena<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">67 km von Pisa\u00a0<\/span><span style=\"font-weight: 400;\">entfernt<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00d6ko-Ferienhaus Le Lavande Kommen Sie und verbringen Sie einen erholsamen Aufenthalt inmitten der Natur, des guten Essens und der landschaftlichen sowie kulturellen Sch\u00f6nheiten der Toskana, alles in einer einladenden und \u00f6kologischen Ferienanlage! Unsere Ferienanlage befindet sich: 27 km von Firenze 37 Km von San Gimignano 42 Km von Vinci 57 km von Siena 67 km [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":344,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates-custom\/tpl-comearrivare.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-337","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz<\/title>\n<meta name=\"description\" content=\"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz\" \/>\n<meta property=\"og:description\" content=\"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Lavande House\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T09:38:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/\",\"url\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/\",\"name\":\"So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz\",\"isPartOf\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg\",\"datePublished\":\"2018-07-16T12:51:35+00:00\",\"dateModified\":\"2025-04-29T09:38:06+00:00\",\"description\":\"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage\",\"url\":\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg\",\"contentUrl\":\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg\",\"width\":1920,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lelavandehouse.com\/de\/homepage\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anfahrt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lelavandehouse.com\/#website\",\"url\":\"https:\/\/www.lelavandehouse.com\/\",\"name\":\"Le Lavande House\",\"description\":\"Un nuovo sito targato WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lelavandehouse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lelavandehouse.com\/#organization\",\"name\":\"Le Lavande House\",\"url\":\"https:\/\/www.lelavandehouse.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.lelavandehouse.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/logo.png\",\"contentUrl\":\"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/logo.png\",\"width\":267,\"height\":219,\"caption\":\"Le Lavande House\"},\"image\":{\"@id\":\"https:\/\/www.lelavandehouse.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz","description":"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/","og_locale":"de_DE","og_type":"article","og_title":"So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz","og_description":"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub","og_url":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/","og_site_name":"Le Lavande House","article_modified_time":"2025-04-29T09:38:06+00:00","og_image":[{"width":1920,"height":617,"url":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/","url":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/","name":"So erreichen Sie die Ortschaft Bottinaccio in Montespertoli in der N\u00e4he von Florenz","isPartOf":{"@id":"https:\/\/www.lelavandehouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage"},"image":{"@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg","datePublished":"2018-07-16T12:51:35+00:00","dateModified":"2025-04-29T09:38:06+00:00","description":"Informationen \u00fcber die Anfahrt zur Ortschaft Bottinaccio in Montespertoli (Florenz), einem landwirtschaftlichen Gebiet zwischen dem Chianti-Gebiet und dem Pesa-Tal, ideal f\u00fcr einen erholsamen Urlaub","breadcrumb":{"@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lelavandehouse.com\/de\/anfahrt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#primaryimage","url":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg","contentUrl":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/slide_comearrivare.jpg","width":1920,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/www.lelavandehouse.com\/de\/anfahrt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lelavandehouse.com\/de\/homepage\/"},{"@type":"ListItem","position":2,"name":"Anfahrt"}]},{"@type":"WebSite","@id":"https:\/\/www.lelavandehouse.com\/#website","url":"https:\/\/www.lelavandehouse.com\/","name":"Le Lavande House","description":"Un nuovo sito targato WordPress","publisher":{"@id":"https:\/\/www.lelavandehouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lelavandehouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lelavandehouse.com\/#organization","name":"Le Lavande House","url":"https:\/\/www.lelavandehouse.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lelavandehouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/logo.png","contentUrl":"https:\/\/www.lelavandehouse.com\/wp-content\/uploads\/2018\/07\/logo.png","width":267,"height":219,"caption":"Le Lavande House"},"image":{"@id":"https:\/\/www.lelavandehouse.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/pages\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/comments?post=337"}],"version-history":[{"count":4,"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/pages\/337\/revisions"}],"predecessor-version":[{"id":618,"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/pages\/337\/revisions\/618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/media\/344"}],"wp:attachment":[{"href":"https:\/\/www.lelavandehouse.com\/de\/wp-json\/wp\/v2\/media?parent=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}